{"id":14,"date":"2022-08-01T16:41:22","date_gmt":"2022-08-01T16:41:22","guid":{"rendered":"https:\/\/pre.conjuntoshistoricoscaceres.com\/?page_id=14"},"modified":"2022-08-27T12:04:10","modified_gmt":"2022-08-27T10:04:10","slug":"conjuntos-historicos-caceres-2","status":"publish","type":"page","link":"https:\/\/conjuntoshistoricoscaceres.com\/2026\/conjuntos-historicos-caceres-2\/","title":{"rendered":"Centros Hist\u00f3ricos C\u00e1ceres"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"14\" class=\"elementor elementor-14\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cd7f967 elementor-section-full_width elementor-section-height-min-height elementor-section-height-default elementor-section-items-middle\" data-id=\"cd7f967\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-945bb68\" data-id=\"945bb68\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-710695f elementor-widget elementor-widget-heading\" data-id=\"710695f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Conjuntos Hist\u00f3ricos<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cdf55d4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cdf55d4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c693682\" data-id=\"c693682\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7780f2c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7780f2c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c01ec83\" data-id=\"c01ec83\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-becb62d elementor-widget elementor-widget-heading\" data-id=\"becb62d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">C\u00e1ceres<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3234ef2 elementor-widget elementor-widget-text-editor\" data-id=\"3234ef2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Alguien me dijo alguna vez que C\u00e1ceres preserva en su ciudad monumental el encanto del tiempo detenido. No es cierto. Para m\u00ed, la ciudad discurre en varias \u00e9pocas a la vez. Siento que tiene la capacidad de trasladarme, a trav\u00e9s de sus monumentos y su historia, a las diferentes civilizaciones que la poblaron y la transformaron cultural, social y econ\u00f3micamente. Nos encontramos ante una ciudad patrimonio de la humanidad dede 1986 y declarada tercer conjunto monumental de Europa. Ven a descubrir los secretos que se ocultan entre sus muros. C\u00e1ceres te espera.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-af208e3\" data-id=\"af208e3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-77137c4 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"77137c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;rollIn&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"417\" height=\"417\" src=\"https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-content\/uploads\/2022\/08\/cconjuntos-historicos-07.png\" class=\"attachment-large size-large wp-image-77\" alt=\"C\u00e1ceres\" srcset=\"https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-content\/uploads\/2022\/08\/cconjuntos-historicos-07.png 417w, https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-content\/uploads\/2022\/08\/cconjuntos-historicos-07-300x300.png 300w, https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-content\/uploads\/2022\/08\/cconjuntos-historicos-07-150x150.png 150w\" sizes=\"(max-width: 417px) 100vw, 417px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-df59970 elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"df59970\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3ff3c38\" data-id=\"3ff3c38\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f53f5a2 elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f53f5a2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c67f393\" data-id=\"c67f393\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f6a5f34 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"f6a5f34\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;rollIn&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"417\" height=\"417\" src=\"https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-content\/uploads\/2022\/08\/cconjuntos-historicos-08.png\" class=\"attachment-large size-large wp-image-78\" alt=\"Cabezuela del valle\" srcset=\"https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-content\/uploads\/2022\/08\/cconjuntos-historicos-08.png 417w, https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-content\/uploads\/2022\/08\/cconjuntos-historicos-08-300x300.png 300w, https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-content\/uploads\/2022\/08\/cconjuntos-historicos-08-150x150.png 150w\" sizes=\"(max-width: 417px) 100vw, 417px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5814592\" data-id=\"5814592\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cdc1e6c elementor-widget elementor-widget-heading\" data-id=\"cdc1e6c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Cabezuela del valle<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-90f7500 elementor-widget elementor-widget-text-editor\" data-id=\"90f7500\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">La naturaleza y la arquitectura tradicional se entrelazan para tejer un entorno armonioso en Cabezuela del Valle. Se encuentra en la parte central del valle, rodeada por alta arboleda hecho que nos permite descubrirla poco a poco, como si se desperezase. Cabezuela del Valle naci\u00f3 en la Edad Media como un peque\u00f1o n\u00facleo de poblaci\u00f3n llamado La Aldea. En los a\u00f1os siguientes el n\u00famero de habitantes creci\u00f3. Los jud\u00edos descubrieron en ella un lugar agradable para vivir y levantaron una juder\u00eda cuya ampliaci\u00f3n fue autorizada por los Reyes Cat\u00f3licos. Sin embargo, no pudo ejecutarse puesto que en el a\u00f1o 1492 se decret\u00f3 la expulsi\u00f3n de estos de la Pen\u00ednsula Ib\u00e9rica. La comunidad jud\u00eda de Cabezuela del Valle era aut\u00f3noma y ejerc\u00eda un fuerte poder econ\u00f3mico.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ebb8ad1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ebb8ad1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c61d4a9\" data-id=\"c61d4a9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-9566637 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9566637\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f1d54a6\" data-id=\"f1d54a6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-88d524e elementor-widget elementor-widget-heading\" data-id=\"88d524e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Galisteo<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d7a40f5 elementor-widget elementor-widget-text-editor\" data-id=\"d7a40f5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Desde el horizonte se divisan magn\u00edficamente conservadas las murallas de Galisteo. Su perfil habla de un pasado hist\u00f3rico y defensivo, probablemente de origen vet\u00f3n, aunque no he encontrado evidencias documentales de ello. Es, sin embargo, durante su colonizaci\u00f3n por los Almohades cuando goza de mayor esplendor patrimonial. La puerta del Rey me recibe, invit\u00e1ndome a entrar y a descubrir su belleza oculta y protegida por su infranqueable muralla.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-cbedc93\" data-id=\"cbedc93\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0f8e2aa elementor-invisible elementor-widget elementor-widget-image\" data-id=\"0f8e2aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;rollIn&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"417\" height=\"417\" src=\"https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-content\/uploads\/2022\/08\/cconjuntos-historicos-09.png\" class=\"attachment-large size-large wp-image-79\" alt=\"BROZAS\" srcset=\"https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-content\/uploads\/2022\/08\/cconjuntos-historicos-09.png 417w, https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-content\/uploads\/2022\/08\/cconjuntos-historicos-09-300x300.png 300w, https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-content\/uploads\/2022\/08\/cconjuntos-historicos-09-150x150.png 150w\" sizes=\"(max-width: 417px) 100vw, 417px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-06eabfe elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"06eabfe\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3f79ca7\" data-id=\"3f79ca7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-db4829c elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"db4829c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b089a69\" data-id=\"b089a69\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7896861 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"7896861\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;rollIn&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"417\" height=\"417\" src=\"https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-content\/uploads\/2022\/08\/cconjuntos-historicos-11.png\" class=\"attachment-large size-large wp-image-96\" alt=\"Garganta la olla\" srcset=\"https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-content\/uploads\/2022\/08\/cconjuntos-historicos-11.png 417w, https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-content\/uploads\/2022\/08\/cconjuntos-historicos-11-300x300.png 300w, https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-content\/uploads\/2022\/08\/cconjuntos-historicos-11-150x150.png 150w\" sizes=\"(max-width: 417px) 100vw, 417px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-cbee045\" data-id=\"cbee045\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3900b45 elementor-widget elementor-widget-heading\" data-id=\"3900b45\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Garganta la Olla<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c28b27a elementor-widget elementor-widget-text-editor\" data-id=\"c28b27a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Antes de comenzar el recorrido hay que detenerse para contemplar sus edificaciones. El ingenio de sus arquitectos hace que todo contribuya a construir una imagen equilibrada entre los materiales de construcci\u00f3n, sus balcones sobresalientes y hasta las flores. \u00bfC\u00f3mo consiguieron este curioso efecto? Muy sencillo, con el uso de materiales de la zona. As\u00ed, se produce un efecto de camuflaje por la continuidad entre el paisaje natural y rural con el urbano, por el gris\u00e1ceo de las calles y el uso de maderas centenarias colocadas en balaustradas y portadas.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0204786 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0204786\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-35abf81\" data-id=\"35abf81\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e4f507a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e4f507a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-8ded099\" data-id=\"8ded099\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2668cd7 elementor-widget elementor-widget-heading\" data-id=\"2668cd7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Granadilla<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-48e837c elementor-widget elementor-widget-text-editor\" data-id=\"48e837c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Visitar la Tierra de Granadilla es conocer a la Peque\u00f1a Granada. A pesar de ser un pueblo abandonado debido a su desalojo en el a\u00f1o 1964, Granadilla late m\u00e1s viva que nunca. La declaraci\u00f3n como conjunto hist\u00f3rico en el a\u00f1o 1980 impuls\u00f3 la rehabilitaci\u00f3n del castillo y la muralla. Con posterioridad, ingres\u00f3 en el programa de recuperaci\u00f3n de pueblos abandonados y cada a\u00f1o es visitada por alumnos de diferentes partes de Espa\u00f1a para trabajar en su rehabilitaci\u00f3n.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-51dd950\" data-id=\"51dd950\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-159f6d4 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"159f6d4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;rollIn&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"417\" height=\"417\" src=\"https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-content\/uploads\/2022\/08\/cconjuntos-historicos-12.png\" class=\"attachment-large size-large wp-image-82\" alt=\"GRANADILLA\" srcset=\"https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-content\/uploads\/2022\/08\/cconjuntos-historicos-12.png 417w, https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-content\/uploads\/2022\/08\/cconjuntos-historicos-12-300x300.png 300w, https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-content\/uploads\/2022\/08\/cconjuntos-historicos-12-150x150.png 150w\" sizes=\"(max-width: 417px) 100vw, 417px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b987d02 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b987d02\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6d7083d\" data-id=\"6d7083d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5e64b71 elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5e64b71\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e17837b\" data-id=\"e17837b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cd97e48 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"cd97e48\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;rollIn&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"417\" height=\"417\" src=\"https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-content\/uploads\/2022\/08\/cconjuntos-historicos-13.png\" class=\"attachment-large size-large wp-image-83\" alt=\"ROBLEDILLO DE GATA\" srcset=\"https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-content\/uploads\/2022\/08\/cconjuntos-historicos-13.png 417w, https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-content\/uploads\/2022\/08\/cconjuntos-historicos-13-300x300.png 300w, https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-content\/uploads\/2022\/08\/cconjuntos-historicos-13-150x150.png 150w\" sizes=\"(max-width: 417px) 100vw, 417px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3b4bf81\" data-id=\"3b4bf81\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5690fe6 elementor-widget elementor-widget-heading\" data-id=\"5690fe6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Robledillo de Gata<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d0a5a0 elementor-widget elementor-widget-text-editor\" data-id=\"6d0a5a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Robledillo de Gata se descubre t\u00edmidamente entre las laderas de la sierra de Gata. Su ubicaci\u00f3n ha permitido que sobreviva intacta puesto que qued\u00f3 como dormida, al margen de la historia. Y este hecho ha dejado una huella tan profunda en la villa que parece que, m\u00e1s que de piedra, est\u00e1 tejida de los usos y costumbres de sus habitantes. Sentir\u00e1s al llegar que te encuentras a punto de formar parte de un misterioso cuento, convirti\u00e9ndome en un personaje m\u00e1s de su historia&#8230;<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-30e97b3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"30e97b3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cf331bc\" data-id=\"cf331bc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7491e91 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7491e91\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-563a31f\" data-id=\"563a31f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8f7f6d8 elementor-widget elementor-widget-heading\" data-id=\"8f7f6d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Pasar\u00f3n de la Vera<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c60a983 elementor-widget elementor-widget-text-editor\" data-id=\"c60a983\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">El emperador Carlos V y su estirpe me siguen hasta mi siguiente destino. La leyenda de amor entre Magdalena Manrique de Lara y don Juan de Austria Jerom\u00edn en aquella \u00e9poca &#8211; durante el verano de 1585, tiene como escenario el palacio de arquitectura renacentista de los Condes de Osorno. Me pregunt\u00f3 qu\u00e9 esconde de verdad y qu\u00e9 de leyenda la historia que une a estos dos j\u00f3venes en uno de los palacios m\u00e1s monumentales de la comarca. Me dispongo a descubrir que rodea a la leyenda de ambos j\u00f3venes y al conjunto hist\u00f3rico art\u00edstico de Pasar\u00f3n de la Vera.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b642241\" data-id=\"b642241\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1a3807b elementor-invisible elementor-widget elementor-widget-image\" data-id=\"1a3807b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;rollIn&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"417\" height=\"417\" src=\"https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-content\/uploads\/2022\/08\/cconjuntos-historicos-14.png\" class=\"attachment-large size-large wp-image-84\" alt=\"PASAR\u00d3N DE LA VERA\" srcset=\"https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-content\/uploads\/2022\/08\/cconjuntos-historicos-14.png 417w, https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-content\/uploads\/2022\/08\/cconjuntos-historicos-14-300x300.png 300w, https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-content\/uploads\/2022\/08\/cconjuntos-historicos-14-150x150.png 150w\" sizes=\"(max-width: 417px) 100vw, 417px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c2c9f33 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c2c9f33\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-75e3bc6\" data-id=\"75e3bc6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e467baa elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e467baa\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-41f8a9a\" data-id=\"41f8a9a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3368ed5 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"3368ed5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;rollIn&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"417\" height=\"417\" src=\"https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-content\/uploads\/2022\/08\/cconjuntos-historicos-15.png\" class=\"attachment-large size-large wp-image-85\" alt=\"VILLANUEVA DE LA VERA\" srcset=\"https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-content\/uploads\/2022\/08\/cconjuntos-historicos-15.png 417w, https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-content\/uploads\/2022\/08\/cconjuntos-historicos-15-300x300.png 300w, https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-content\/uploads\/2022\/08\/cconjuntos-historicos-15-150x150.png 150w\" sizes=\"(max-width: 417px) 100vw, 417px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e467fae\" data-id=\"e467fae\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4d9a789 elementor-widget elementor-widget-heading\" data-id=\"4d9a789\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Villanueva de la Vera<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dc5af2e elementor-widget elementor-widget-text-editor\" data-id=\"dc5af2e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">La comarca de La Vera es afamada por sus gargantas y por su belleza natural, sin embargo, guarda celosa cinco conjuntos hist\u00f3rico-art\u00edsticos que podr\u00e1s descubrir. Villanueva de la Vera es mi primer destino. Se trata de una villa fundada a finales del siglo XII y, a trav\u00e9s de sus monumentos y su arquitectura popular, me traslada la belleza de la esencia rural. Villanueva de la Vera no es lugar de artificios. Te recibir\u00e1 silenciosa y te gu\u00eda a trav\u00e9s de las regateras, canales de agua que se encuentran en el centro de las calles y que nerviosos las recorren hasta desembocar en los huertos.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8063280 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8063280\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-17263ed\" data-id=\"17263ed\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7cb195d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7cb195d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4dc3fc6\" data-id=\"4dc3fc6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bcab9f2 elementor-widget elementor-widget-heading\" data-id=\"bcab9f2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Herv\u00e1s<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-307d698 elementor-widget elementor-widget-text-editor\" data-id=\"307d698\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">No resulta extra\u00f1o que este peculiar dicho se hiciera popular en Herv\u00e1s puesto que cuenta con una de las juder\u00edas mejor conservadas de Espa\u00f1a. Aunque los jud\u00edos tuvieron un papel relevante en varios de los conjuntos hist\u00f3ricos que he visitado hasta ahora, es Herv\u00e1s la que con m\u00e1s mimo ha preservado los vestigios de la cultura sefard\u00ed. Penetrar en ella es adentrarse en la vor\u00e1gine de calles estrechas, empinadas y sin orden aparente; pero tambi\u00e9n es descubrir sus costumbres, su cultura y sobre todo la historia que les llev\u00f3 en 1492 a abandonar la villa o a convertirse al cristianismo.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1963c0e\" data-id=\"1963c0e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-63befe0 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"63befe0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;rollIn&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"417\" height=\"417\" src=\"https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-content\/uploads\/2022\/08\/cconjuntos-historicos-16.png\" class=\"attachment-large size-large wp-image-86\" alt=\"HERVAS\" srcset=\"https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-content\/uploads\/2022\/08\/cconjuntos-historicos-16.png 417w, https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-content\/uploads\/2022\/08\/cconjuntos-historicos-16-300x300.png 300w, https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-content\/uploads\/2022\/08\/cconjuntos-historicos-16-150x150.png 150w\" sizes=\"(max-width: 417px) 100vw, 417px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6925f12 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6925f12\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3b57eec\" data-id=\"3b57eec\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7feaec5 elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7feaec5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-dfdc3a7\" data-id=\"dfdc3a7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-805ca6f elementor-invisible elementor-widget elementor-widget-image\" data-id=\"805ca6f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;rollIn&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"417\" height=\"417\" src=\"https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-content\/uploads\/2022\/08\/cconjuntos-historicos-17.png\" class=\"attachment-large size-large wp-image-87\" alt=\"CUACOS DE YUSTE\" srcset=\"https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-content\/uploads\/2022\/08\/cconjuntos-historicos-17.png 417w, https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-content\/uploads\/2022\/08\/cconjuntos-historicos-17-300x300.png 300w, https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-content\/uploads\/2022\/08\/cconjuntos-historicos-17-150x150.png 150w\" sizes=\"(max-width: 417px) 100vw, 417px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-022d868\" data-id=\"022d868\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c417d57 elementor-widget elementor-widget-heading\" data-id=\"c417d57\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Cuacos de Yuste<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-224459c elementor-widget elementor-widget-text-editor\" data-id=\"224459c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Cuacos de Yuste se encuentra marcada hist\u00f3ricamente por ser el lugar de descanso imperial de Carlos V. Sin embargo, sus calles y su patrimonio, fueron declarados paraje pintoresco en el a\u00f1o 1959 y con posterioridad catalogados como conjunto hist\u00f3rico art\u00edstico. Cuacos alberga el encanto de las callejuelas que serpentean entre plazas coronadas por fuentes de agua clara y limpia que proviene de la sierra. Me parece una localidad inconfundible no solo por su historia, que la convierte en \u00fanica, sino por la belleza y la singularidad de algunos rincones que me dispongo a conocer.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2a67947 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2a67947\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cb95f91\" data-id=\"cb95f91\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-560c736 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"560c736\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a2b6669\" data-id=\"a2b6669\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4c48367 elementor-widget elementor-widget-heading\" data-id=\"4c48367\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Brozas<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-835823e elementor-widget elementor-widget-text-editor\" data-id=\"835823e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Brozas forma un matrimonio indisoluble con la nobleza y los caballeros. Con testimonios que comienzan en la Prehistoria, contin\u00faan en la \u00e9poca romana, con restos bien conservados de la calzada romana \u00abV\u00eda da Estrela\u00bb que atraviesa la localidad, hasta desembocar en la Edad Media y Moderna, momentos de m\u00e1ximo esplendor hist\u00f3rico, en los que se construyen los principales monumentos de la villa, all\u00e1 por el siglo XV.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-32f0475\" data-id=\"32f0475\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-df2b737 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"df2b737\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;rollIn&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"417\" height=\"417\" src=\"https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-content\/uploads\/2022\/08\/cconjuntos-historicos-18.png\" class=\"attachment-large size-large wp-image-88\" alt=\"BROZAS\" srcset=\"https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-content\/uploads\/2022\/08\/cconjuntos-historicos-18.png 417w, https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-content\/uploads\/2022\/08\/cconjuntos-historicos-18-300x300.png 300w, https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-content\/uploads\/2022\/08\/cconjuntos-historicos-18-150x150.png 150w\" sizes=\"(max-width: 417px) 100vw, 417px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-77fc278 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"77fc278\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5662fa3\" data-id=\"5662fa3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f99fd3b elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f99fd3b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-20f0e12\" data-id=\"20f0e12\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2fb6a64 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"2fb6a64\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;rollIn&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"417\" height=\"417\" src=\"https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-content\/uploads\/2022\/08\/cconjuntos-historicos-19.png\" class=\"attachment-large size-large wp-image-89\" alt=\"CORIA\" srcset=\"https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-content\/uploads\/2022\/08\/cconjuntos-historicos-19.png 417w, https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-content\/uploads\/2022\/08\/cconjuntos-historicos-19-300x300.png 300w, https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-content\/uploads\/2022\/08\/cconjuntos-historicos-19-150x150.png 150w\" sizes=\"(max-width: 417px) 100vw, 417px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5d2d2fe\" data-id=\"5d2d2fe\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9843027 elementor-widget elementor-widget-heading\" data-id=\"9843027\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Coria<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ec311d elementor-widget elementor-widget-text-editor\" data-id=\"2ec311d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Desde su puente se divisa su imponente conjunto hist\u00f3rico presidido por la catedral y recuerdo las palabras de Ortega y Gasset \u00abUna ciudad inveros\u00edmil, torva e inm\u00f3vil como un susto en medio de un camino\u00bb. Atravesar sus murallas para conocerla con ojos de descubridor, como lo hicieron en su d\u00eda vettones, romanos, visigodos o musulmanes. Numerosas son las culturas y las civilizaciones que decidieron asentarse en Coria. Sobre todo por su posici\u00f3n privilegiada, a los pies del r\u00edo Alag\u00f3n, dominando la llanura.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-563ef69 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"563ef69\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a0c6036\" data-id=\"a0c6036\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5e60b5c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5e60b5c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f50cd2a\" data-id=\"f50cd2a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d07e8ed elementor-widget elementor-widget-heading\" data-id=\"d07e8ed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Gata<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-23a46c0 elementor-widget elementor-widget-text-editor\" data-id=\"23a46c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Custodiada por la torre de la Almenara, a menos de media legua, se halla Gata. Sus or\u00edgenes son hist\u00f3ricos puesto que, antes de ser villa fue nombrada cat\u00f3briga por los romanos y albaranes por los \u00e1rabes. Sus contiendas a lo largo de los a\u00f1os y la importancia de la Orden de Alc\u00e1ntara en su evoluci\u00f3n, la convierten en uno de los lugares m\u00e1s interesantes de la Sierra de Gata. La villa de Gata, declarada conjunto hist\u00f3rico art\u00edstico en 1995, comienza en la plaza de la Constituci\u00f3n en la que destaca el ayuntamiento, la iglesia de san Pedro y la fuente del Chorro.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e9eb0c2\" data-id=\"e9eb0c2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-132b294 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"132b294\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;rollIn&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"417\" height=\"417\" src=\"https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-content\/uploads\/2022\/08\/cconjuntos-historicos-20.png\" class=\"attachment-large size-large wp-image-90\" alt=\"VALVERDE DE LA VERA\" srcset=\"https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-content\/uploads\/2022\/08\/cconjuntos-historicos-20.png 417w, https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-content\/uploads\/2022\/08\/cconjuntos-historicos-20-300x300.png 300w, https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-content\/uploads\/2022\/08\/cconjuntos-historicos-20-150x150.png 150w\" sizes=\"(max-width: 417px) 100vw, 417px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6150ce6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6150ce6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e84c89f\" data-id=\"e84c89f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ac88204 elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ac88204\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7b0f32a\" data-id=\"7b0f32a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-eeaf222 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"eeaf222\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;rollIn&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"417\" height=\"417\" src=\"https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-content\/uploads\/2022\/08\/cconjuntos-historicos-21.png\" class=\"attachment-large size-large wp-image-91\" alt=\"guadalupe\" srcset=\"https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-content\/uploads\/2022\/08\/cconjuntos-historicos-21.png 417w, https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-content\/uploads\/2022\/08\/cconjuntos-historicos-21-300x300.png 300w, https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-content\/uploads\/2022\/08\/cconjuntos-historicos-21-150x150.png 150w\" sizes=\"(max-width: 417px) 100vw, 417px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b3d54de\" data-id=\"b3d54de\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-81d0a73 elementor-widget elementor-widget-heading\" data-id=\"81d0a73\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Guadalupe<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-08e9d87 elementor-widget elementor-widget-text-editor\" data-id=\"08e9d87\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Guadalupe es algo m\u00e1s que un monasterio, aunque \u00e9ste sea el motivo de que cientos de personas peregrinen cada a\u00f1o hasta este bello lugar enclavado en la sierra de las Villuercas. Se trata de una puebla marcada por la figura de la virgen y su leyenda. Sin embargo, Guadalupe cuenta con un fabuloso legado patrimonial cultivado entre los siglos XV y XVI. Arcos medievales, plazas hist\u00f3ricas, preciosas calles engalanadas con macetas y varios hospitales adem\u00e1s de la iglesia parroquial de la sant\u00edsima Trinidad convierten la visita a en toda una experiencia.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-993767b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"993767b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6c5b1f7\" data-id=\"6c5b1f7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-938fdcc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"938fdcc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3662f73\" data-id=\"3662f73\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-162869a elementor-widget elementor-widget-heading\" data-id=\"162869a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Valverde de la Vera<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-87c70b4 elementor-widget elementor-widget-text-editor\" data-id=\"87c70b4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Valverde de la Vera cuenta con el encanto tradicional verato. Sus calles empedradas y su arquitectura, similar en caracter\u00edsticas y en materiales a la de Villanueva de la Vera, narran la historia de una villa que alcanz\u00f3 su gloria y esplendor entre los siglos XII y XV. Su conjunto hist\u00f3rico es algo m\u00e1s que su patrimonio. Su entorno y su conjunto rural lo convierten en merecedor del t\u00edtulo que ostenta desde los a\u00f1os 70.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5a32f94\" data-id=\"5a32f94\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e8edbf9 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"e8edbf9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;rollIn&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"417\" height=\"417\" src=\"https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-content\/uploads\/2022\/08\/valverdedelavera-25.jpg\" class=\"attachment-large size-large wp-image-1940\" alt=\"Valverde de la Vera\" srcset=\"https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-content\/uploads\/2022\/08\/valverdedelavera-25.jpg 417w, https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-content\/uploads\/2022\/08\/valverdedelavera-25-300x300.jpg 300w, https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-content\/uploads\/2022\/08\/valverdedelavera-25-150x150.jpg 150w\" sizes=\"(max-width: 417px) 100vw, 417px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-73e4691 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"73e4691\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a2f3303\" data-id=\"a2f3303\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-15aedb8 elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"15aedb8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-0e7fff8\" data-id=\"0e7fff8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-588c163 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"588c163\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;rollIn&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"417\" height=\"417\" src=\"https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-content\/uploads\/2022\/08\/cconjuntos-historicos-23.png\" class=\"attachment-large size-large wp-image-93\" alt=\"TRUJILLO\" srcset=\"https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-content\/uploads\/2022\/08\/cconjuntos-historicos-23.png 417w, https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-content\/uploads\/2022\/08\/cconjuntos-historicos-23-300x300.png 300w, https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-content\/uploads\/2022\/08\/cconjuntos-historicos-23-150x150.png 150w\" sizes=\"(max-width: 417px) 100vw, 417px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-8ad29c7\" data-id=\"8ad29c7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-86d1863 elementor-widget elementor-widget-heading\" data-id=\"86d1863\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Trujillo<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4970948 elementor-widget elementor-widget-text-editor\" data-id=\"4970948\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">La magn\u00edfica Trujillo, denominada Turgalium por los romanos, siempre ha sido un referente hist\u00f3rico. Llegar a la plaza Mayor y situarme frente a la estatua de Pizarro y a su conjunto hist\u00f3rico me llena de impaciencia. Ante m\u00ed se encuentra la historia de los conquistadores, aquellos que durante el siglo XV y XVI convirtieron Trujillo en un referente arquitect\u00f3nico por su revoluci\u00f3n, fruto del enriquecimiento por el descubrimiento del nuevo mundo.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-453a3f8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"453a3f8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b01b24f\" data-id=\"b01b24f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-beb18e9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"beb18e9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-bc7686a\" data-id=\"bc7686a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b28ebe0 elementor-widget elementor-widget-heading\" data-id=\"b28ebe0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Valencia de Alc\u00e1ntara<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-44b0989 elementor-widget elementor-widget-text-editor\" data-id=\"44b0989\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Rodeada por tres formaciones monta\u00f1osas, esta localidad est\u00e1 situada dentro del parque natural Tajo Internacional. Fundada por los romanos (Valentia), qued\u00f3 en manos de los visigodos hasta el siglo XIII. Su proximidad a Portugal marca los siglos siguientes hasta que la villa vive sus mejores momentos entre el XVI y el XVII, con la construcci\u00f3n de sus monumentos m\u00e1s representativos. El municipio cacere\u00f1o posee el t\u00edtulo de \u00abmuy noble, antigua y leal villa\u00bb. El hecho de colindar con Portugal le ha conferido desde su fundaci\u00f3n una gran importancia hist\u00f3rica e incluso perteneci\u00f3 al reino de Portugal entre 1644 y 1668.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e5e29dd\" data-id=\"e5e29dd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0f1f06a elementor-invisible elementor-widget elementor-widget-image\" data-id=\"0f1f06a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;rollIn&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"417\" height=\"417\" src=\"https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-content\/uploads\/2022\/08\/cconjuntos-historicos-24.png\" class=\"attachment-large size-large wp-image-94\" alt=\"VALENCIA DE ALC\u00c1NTARA\" srcset=\"https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-content\/uploads\/2022\/08\/cconjuntos-historicos-24.png 417w, https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-content\/uploads\/2022\/08\/cconjuntos-historicos-24-300x300.png 300w, https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-content\/uploads\/2022\/08\/cconjuntos-historicos-24-150x150.png 150w\" sizes=\"(max-width: 417px) 100vw, 417px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0ccde60 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0ccde60\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c49e43d\" data-id=\"c49e43d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-db23882 elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"db23882\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-17ab7dd elementor-invisible\" data-id=\"17ab7dd\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;rollIn&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c131cd2 elementor-widget elementor-widget-image\" data-id=\"c131cd2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"417\" height=\"417\" src=\"https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-content\/uploads\/2022\/08\/cconjuntos-historicos-25.png\" class=\"attachment-large size-large wp-image-95\" alt=\"PLASENCIA\" srcset=\"https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-content\/uploads\/2022\/08\/cconjuntos-historicos-25.png 417w, https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-content\/uploads\/2022\/08\/cconjuntos-historicos-25-300x300.png 300w, https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-content\/uploads\/2022\/08\/cconjuntos-historicos-25-150x150.png 150w\" sizes=\"(max-width: 417px) 100vw, 417px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6cb410e\" data-id=\"6cb410e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b840981 elementor-widget elementor-widget-heading\" data-id=\"b840981\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Plasencia<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-409b952 elementor-widget elementor-widget-text-editor\" data-id=\"409b952\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Se trata de una plaza porticada y presidida por el ayuntamiento y su torre renacentista. En ella se encuentra uno de los elementos m\u00e1s queridos por los placentinos, El Abuelo Mayorga, un campanero que lleva desde 1743 cantando las horas. Aunque ha sufrido distintas restauraciones e incluso fue destruido por los franceses, el pueblo de Plasencia siembre lo ha devuelto a su lugar, en lo alto De la Torre desde donde vigila la plaza.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c171b9a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c171b9a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b4cdba2\" data-id=\"b4cdba2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5e85d47 elementor-widget elementor-widget-spacer\" data-id=\"5e85d47\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c179473 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"c179473\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-408f427\" data-id=\"408f427\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e0100f6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e0100f6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a03b958\" data-id=\"a03b958\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f7001a9 elementor-widget elementor-widget-heading\" data-id=\"f7001a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Descarga la gu\u00eda de Conjuntos Hist\u00f3ricos de la provincia de C\u00e1ceres<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bf8e5a9 elementor-widget elementor-widget-text-editor\" data-id=\"bf8e5a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Una publicaci\u00f3n amena e ilustrada para descubrir toda la informaci\u00f3n sobre los Conjuntos Hist\u00f3ricos de la provincia.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-244d0a1 elementor-align-left elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"244d0a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-content\/uploads\/2022\/08\/guia-conjuntos-historicos-provincia-de-caceres-2022.pdf\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">DESCARGAR<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f853a57\" data-id=\"f853a57\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cdc296c elementor-widget elementor-widget-image\" data-id=\"cdc296c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/pre.conjuntoshistoricoscaceres.com\/wp-content\/uploads\/2022\/08\/guia-conjuntos-historicos-provincia-de-caceres-2022.pdf\" target=\"_blank\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"829\" height=\"1024\" src=\"https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-content\/uploads\/2022\/08\/guia-conjuntos-historios-portada-829x1024.jpg\" class=\"elementor-animation-grow attachment-large size-large wp-image-1706\" alt=\"guia-conjuntos-historios-provincia-de-caceres\" srcset=\"https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-content\/uploads\/2022\/08\/guia-conjuntos-historios-portada-829x1024.jpg 829w, https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-content\/uploads\/2022\/08\/guia-conjuntos-historios-portada-243x300.jpg 243w, https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-content\/uploads\/2022\/08\/guia-conjuntos-historios-portada-768x949.jpg 768w, https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-content\/uploads\/2022\/08\/guia-conjuntos-historios-portada-1243x1536.jpg 1243w, https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-content\/uploads\/2022\/08\/guia-conjuntos-historios-portada.jpg 1282w\" sizes=\"(max-width: 829px) 100vw, 829px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a5a5153 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"a5a5153\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;sticky&quot;:&quot;bottom&quot;,&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;sticky_offset&quot;:0,&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c440c18\" data-id=\"c440c18\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a196338 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"a196338\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/conjuntoshistoricoscaceres.com\/2026\/conjuntos-historicos-caceres-2\/#\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-circle-up\"><\/i>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Conjuntos Hist\u00f3ricos C\u00e1ceres Alguien me dijo alguna vez que C\u00e1ceres preserva en su ciudad monumental el encanto del tiempo detenido. No es cierto. Para m\u00ed, la ciudad discurre en varias \u00e9pocas a la vez. Siento que tiene la capacidad de trasladarme, a trav\u00e9s de sus monumentos y su historia, a las diferentes civilizaciones que la [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_canvas","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-14","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-json\/wp\/v2\/pages\/14","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-json\/wp\/v2\/comments?post=14"}],"version-history":[{"count":437,"href":"https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-json\/wp\/v2\/pages\/14\/revisions"}],"predecessor-version":[{"id":1946,"href":"https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-json\/wp\/v2\/pages\/14\/revisions\/1946"}],"wp:attachment":[{"href":"https:\/\/conjuntoshistoricoscaceres.com\/2026\/wp-json\/wp\/v2\/media?parent=14"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}